{"id":19103,"date":"2014-11-26T16:30:09","date_gmt":"2014-11-26T21:30:09","guid":{"rendered":"http:\/\/www.noahholt.com\/blog\/?p=19103"},"modified":"2014-11-19T12:16:53","modified_gmt":"2014-11-19T17:16:53","slug":"ps-133-fall-festival","status":"publish","type":"post","link":"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/","title":{"rendered":"PS 133 Fall Festival"},"content":{"rendered":"<p>Noah&#8217;s school, PS 133, holds a Fall Festival every year to build community, raise funds, and have fun.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19104\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31953\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31953.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31953.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31953.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-full wp-image-19104\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31953.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_31953\" width=\"560\" height=\"700\" \/><\/p>\n<p>Kate manning the spin art booth.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19105\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31960\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31960.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31960.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31960.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19105\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31960.jpg?resize=700%2C436&#038;ssl=1\" alt=\"141018_31960\" width=\"700\" height=\"436\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19106\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31967\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31967.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31967.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31967.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19106\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31967.jpg?resize=700%2C560&#038;ssl=1\" alt=\"141018_31967\" width=\"700\" height=\"560\" \/><\/p>\n<p>The candy table is always popular.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19107\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31971\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31971.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31971.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31971.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19107\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31971.jpg?resize=700%2C436&#038;ssl=1\" alt=\"141018_31971\" width=\"700\" height=\"436\" \/><\/p>\n<p>Decorating planters.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19108\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31991\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31991.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31991.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31991.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19108\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31991.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_31991\" width=\"560\" height=\"700\" \/><\/p>\n<p>Decorating pumpkins.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19112\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32007\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32007.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32007.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32007.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19112\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32007.jpg?resize=700%2C560&#038;ssl=1\" alt=\"141018_32007\" width=\"700\" height=\"560\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19120\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32078\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32078.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32078.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32078.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19120\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32078.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32078\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19109\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31992\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31992.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31992.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31992.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19109\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31992.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_31992\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19110\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_31994\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31994.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31994.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31994.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19110\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_31994.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_31994\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19111\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32000\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32000.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32000.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32000.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19111\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32000.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32000\" width=\"560\" height=\"700\" \/><\/p>\n<p>Steel drum band!<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19113\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32010\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32010.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32010.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32010.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19113\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32010.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32010\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19114\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32016\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32016.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32016.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32016.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19114\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32016.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32016\" width=\"560\" height=\"700\" \/><\/p>\n<p>Young sluggah.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19115\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32023\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32023.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32023.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32023.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19115\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32023.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32023\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19116\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32035\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32035.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32035.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32035.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19116\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32035.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32035\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19117\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32037\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32037.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32037.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32037.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19117\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32037.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32037\" width=\"560\" height=\"700\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19121\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32040\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32040.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32040.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32040.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19121\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32040.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32040\" width=\"560\" height=\"700\" \/><\/p>\n<p>A few days before the Fall Festival we found out that Sara, who went to day care with Noah when he was 2-3, was going to be going to PS 133 now!\u00c2\u00a0Here are some\u00c2\u00a0flashback photos of Sara with Savannah, and then another 8 months later pushing Noah at Underhill Playground.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19122\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/kreg-holt-1019\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/110319_8703.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/110319_8703.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/110319_8703.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19122\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/110319_8703.jpg?resize=700%2C436&#038;ssl=1\" alt=\"\u00c2\u00a9 Kreg Holt\" width=\"700\" height=\"436\" \/><\/p>\n<p>Here she is grown up with colorful nails, making some spin art!<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19118\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32064\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32064.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32064.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32064.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19118\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32064.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32064\" width=\"560\" height=\"700\" \/><\/p>\n<p>This guy.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19119\" data-permalink=\"https:\/\/www.noahholt.com\/blog\/2014\/11\/26\/ps-133-fall-festival\/141018_32067\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32067.jpg?fit=%2C&amp;ssl=1\" data-orig-size=\"\" data-comments-opened=\"1\" data-image-meta=\"[]\" data-image- data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32067.jpg?fit=700%2C700&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32067.jpg?fit=700%2C700&amp;ssl=1\" class=\"aligncenter size-large wp-image-19119\" src=\"https:\/\/i0.wp.com\/www.noahholt.com\/blog\/wp-content\/uploads\/2014\/11\/141018_32067.jpg?resize=560%2C700&#038;ssl=1\" alt=\"141018_32067\" width=\"560\" height=\"700\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fun times at the PS 133 Brooklyn Fall Festival.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[43,3,27,59,57],"tags":[],"class_list":["post-19103","post","type-post","status-publish","format-standard","hentry","category-art","category-friends","category-psyched","category-school","category-sports"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pl9oj-4Y7","_links":{"self":[{"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/posts\/19103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/comments?post=19103"}],"version-history":[{"count":4,"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/posts\/19103\/revisions"}],"predecessor-version":[{"id":19126,"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/posts\/19103\/revisions\/19126"}],"wp:attachment":[{"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/media?parent=19103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/categories?post=19103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noahholt.com\/blog\/wp-json\/wp\/v2\/tags?post=19103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}